{"id":1413,"date":"2022-07-29T12:02:56","date_gmt":"2022-07-29T10:02:56","guid":{"rendered":"https:\/\/www.maccaferri.com\/latam\/?page_id=1413"},"modified":"2025-02-06T17:52:58","modified_gmt":"2025-02-06T16:52:58","slug":"centro-de-conocimiento","status":"publish","type":"page","link":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/","title":{"rendered":"Centro de conocimiento"},"content":{"rendered":"<div class=\"wp-block-mac-h1-title-hero-block container-fluid block-txt-container\" style=\"background:linear-gradient(180deg,rgb(1,94,111) 0%,rgb(0,72,87) 100%)\"><div class=\"row\"><div class=\"col\"><div class=\"gts__picture\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg\" style=\"display:none\"\/><div class=\"gts__picture__image\" style=\"background-image:url(https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg)\"><\/div><\/div><div class=\"container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><h1 class=\"wp-block-mac-h1-title-hero-block\" style=\"color:#ffffff;text-align:none\">Centro de conocimiento<\/h1><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><style>\n                .buttonurl.webinarblock_979695767b0f1d04a2317cad96893364 span.buttontext::after\n                {\n                    color: #ed791d !important;\n                }\n                <\/style>\n                <div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\">\n                    <div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f8f9fa\">\n                        <div class=\"wp-block-mac-title-cta-block container box-container orange\" style=\"color:#ed791d;background:#f8f9fa\">\n                            <div class=\"row\">\n                                <div class=\"col-9 title-box-txt\">\n                                    <h2 class=\"wp-block-mac-title-cta-block orange\" style=\"color:#212429;text-align:left\">Pr\u00f3ximos Webinars<\/h2>\n                                <\/div>\n                                <div class=\"col-3 button-box-txt\">\n                                    <a href=\"\" class=\"buttonurl webinarblock_979695767b0f1d04a2317cad96893364\" rel=\"noopener\" style=\"color:#ed791d;\"> \n                                        <span class=\"buttontext\">Todos los Webinars<\/span>\n                                    <\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div><div class=\"wp-block-mac-banner-block-cta block-cta\"><div class=\"container box-container\"><div class=\"row\"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\"><div class=\"box-image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2026\/07\/Background-Webinar-Rockfall-JULY26.jpg\" alt=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2026\/07\/Background-Webinar-Rockfall-JULY26.jpg\"><\/div><\/div><div class=\"col-12 col-sm-12 col-md-12 col-lg-7 col-xl-7 col-xxl-7\"><div class=\"banner-box-txt\"><h5 class=\"title\">23 July 2026<\/h5><p class=\"description\">Safer, Faster, Smarter: Maccaferri Rockfall Barriers<\/p><\/div><\/div><div class=\"col-12 col-sm-12 col-md-12 col-lg-2 col-xl-2 col-xxl-2\"><div class=\"button-box-txt\"><a href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/safer-faster-smarter-maccaferri-rockfall-barriers\/\" class=\"buttonurl\" title=\"Ir al webinar\" rel=\"noopener\">\n                            <span class=\"buttontext\">Reg\u00edstrate ahora<\/span>\n                        <\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><style>\n                .buttonurl.webinarblock_5b2a32a143fde2bb5ed986cdb1ca0f16 span.buttontext::after\n                {\n                    color: #ed791d !important;\n                }\n                <\/style>\n                <div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\">\n                    <div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f8f9fa\">\n                        <div class=\"wp-block-mac-title-cta-block container box-container orange\" style=\"color:#ed791d;background:#f8f9fa\">\n                            <div class=\"row\">\n                                <div class=\"col-9 title-box-txt\">\n                                    <h2 class=\"wp-block-mac-title-cta-block orange\" style=\"color:#212429;text-align:left\">Webinars grabados<\/h2>\n                                <\/div>\n                                <div class=\"col-3 button-box-txt\">\n                                    <a href=\"\" class=\"buttonurl webinarblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" rel=\"noopener\" style=\"color:#ed791d;\"> \n                                        <span class=\"buttontext\">Todos los Webinars<\/span>\n                                    <\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div><div class=\"wp-container wp-block-column carousel-webinar-recordings hbox\"><div class=\"carousel-webinar-recordings container\"><div class=\"row\"><div id=\"carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" class=\"carousel slide carouselwebinarrecordings\" data-bs-ride=\"carousel\"><ol class=\"carousel-indicators\"><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"0\" class=\"active\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"1\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"2\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"3\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"4\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"5\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"6\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"7\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"8\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" data-bs-slide-to=\"9\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><\/ol><a class=\"carousel-control-prev w-aut\" href=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" role=\"button\" data-bs-slide=\"prev\">\n                     <span class=\"carousel-control-prev-icon\" aria-hidden=\"true\"><\/span>\n                  <\/a><a class=\"carousel-control-next w-aut\" href=\"#carouselwebinarrecordingsblock_5b2a32a143fde2bb5ed986cdb1ca0f16\" role=\"button\" data-bs-slide=\"next\">\n                    <span class=\"carousel-control-next-icon\" aria-hidden=\"true\"><\/span>\n                  <\/a> <div class=\"carousel-inner container box-container\" role=\"listbox\"><div class=\"carousel-item active\"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">Advanced gabion walls: design, analysis and durability<\/div><p> Watch the recording.<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/advanced-gabion-walls-design-analysis-and-durability\/\">Ver ahora <\/a><div data-post-id=\"94565\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">Basal Reinforcement Solutions: Designing safer infrastructure on challenging ground<\/div><p> Join us on the 11th!<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/basal-reinforcement-solutions-designing-safer-infrastructure-on-challenging-ground\/\">Ver ahora <\/a><div data-post-id=\"94043\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">MacCycle Assessment: A new way to design more sustainable infrastructure<\/div><p> Join us on May 14th.<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/maccycle-assessment-a-new-way-to-design-more-sustainable-infrastructure\/\">Ver ahora <\/a><div data-post-id=\"92526\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">Gesti\u00f3n del Riesgo de Avalanchas de Nieve: Soluciones e Innovaciones<\/div><p> \u00danase a nosotros el 23 de abril.<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/gestion-del-riesgo-de-avalanchas-de-nieve-soluciones-e-innovaciones\/\">Ver ahora <\/a><div data-post-id=\"91262\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">River training works: a new testing approach to simulate hydraulic conditions<\/div><p> 26\/03\/2026 River training works: a new testing approach to simulate hydraulic conditions Hydraulic structures operate in naturally aggressive environments, especially during flood events, when powerful currents and intense sediment transport generate significant mechanical stress. In these conditions, abrasion resistance is a key performance factor for gabions and Reno Mattresses: if the coating is worn away, [&hellip;]<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/river-training-works-a-new-testing-approach-to-simulate-hydraulic-conditions\/\">Ver ahora <\/a><div data-post-id=\"90475\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">Una nueva era para Soluciones en T\u00faneles<\/div><p> \u00a1\u00danete a nosotros el 5 de marzo!<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/soluciones-en-tuneles-un-nuevo-portafolio-360-construido-sobre-la-innovacion\/\">Ver ahora <\/a><div data-post-id=\"89548\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">Advanced Geocell Technology for Slope Protection<\/div><p> Join us on February 12th!<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/advanced-geocell-technology-for-slope-protection\/\">Ver ahora <\/a><div data-post-id=\"87966\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">GroundMac Design: the software solution for soil stabilization<\/div><p> Watch the recordings.<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/groundmac-design-the-software-solution-for-soil-stabilization\/\">Ver ahora <\/a><div data-post-id=\"81679\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">WEB TALK \u2013 Tecnolog\u00edas y Estrategias para Mitigar la Ca\u00edda de Rocas en Infraestructuras<\/div><p> La ca\u00edda de rocas en carreteras y \u00e1reas monta\u00f1osas representa un desaf\u00edo cr\u00edtico para la seguridad vial y la protecci\u00f3n de infraestructuras.<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/web-talk-tecnologias-y-estrategias-para-mitigar-la-caida-de-rocas-en-infraestructuras\/\">Ver ahora <\/a><div data-post-id=\"84395\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-web-e1667462424828.png\"> <\/div><div class=\"subtitle\">M\u00e1s R\u00e1pido, M\u00e1s Seguro, M\u00e1s Inteligente: Barreras Contra Ca\u00edda de Rocas Maccaferri<\/div><p> \u00a1Reg\u00edstrate ahora!<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/webinar\/faster-safer-smarter-maccaferri-rockfall-barriers\/\">Ver ahora <\/a><div data-post-id=\"73132\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-banner-title-cta  box-container block-cta\" style=\"background:#015E6F\"><div class=\"container box-container\"><div class=\"row\"><div class=\"col-2 col-sm-2 col-md-2 col-lg-2 col-xl-2 col-xxl-2\"><div class=\"box-image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/11\/img-banner-software.png\" alt=\"Image\"\/><\/div><\/div><div class=\"col-7 col-sm-7 col-md-7 col-lg-7 col-xl-7 col-xxl-7\"><div class=\"banner-box-txt\" style=\"text-align:default\"><h4 class=\"title\">USE NUESTROS SOFTWARES<br>PARA PROYECTAR EL FUTURO<\/h4><\/div><\/div><div class=\"col-3 col-sm-3 col-md-3 col-lg-3 col-xl-3 col-xxl-3\"><div class=\"button-box-txt\"><a href=\"https:\/\/www.maccaferri.com\/latam\/paquete-de-softwares-maccaferri\" class=\"buttonurl\" rel=\"noopener\"><span class=\"buttontext\">Secci\u00f3n de Softwares<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"search-block\">\n    <div class=\"wp-container wp-block-column has-white-background-color has-background\">\n        <div class=\"wp-block-mac-h2-title-block block-txt-container box-container\">\n            <div class=\"row\">\n                <div class=\"col-12 title-box-txt\">\n                                            <div class=\"text-center\">\n                            <img decoding=\"async\" src=\"\" style=\"width: px !important; height:px !important;\" alt=\"\">\n                        <\/div>\n                    \n                    <h2 style=\"text-align: center\">Explore the Maccaferri World<\/h2>\n                <\/div>\n            <\/div>\n            <form id=\"main-search-form\" method=\"GET\" action=\"https:\/\/www.maccaferri.com\/latam\/search\/\">\n                <input type=\"hidden\" name=\"category-link\" value=\"\">\n                <div class=\"row\">\n                    <div class=\"col-12\">\n                        <div class=\"form-group position\">\n                            <input type=\"text\" class=\"form-control form-control-lg search\" id=\"search-text\" name=\"r\" value=\"\" placeholder=\"Busque Productos, Soluciones o todo\">\n                            <span class=\"submit-search\"><\/span>\n                        <\/div>\n                    <\/div>\n                <\/div>\n\n                <div class=\"row\">\n                    <div class=\"col-12\">\n                        <div class=\"title\">Filtrar por:<\/div>\n                    <\/div>\n                    <div class=\"col-12 col-lg-3\">\n                        <div class=\"form-group\">\n                            <select class=\"form-control form-control-lg select\" name=\"sectors-select\" id=\"sectors-select\">\n                                <option value=\"\">Sector<\/option>\n                                <option value=\"87801\" >Agroindustria<\/option><option value=\"87798\" >Defensa &#038; Seguridad<\/option><option value=\"87795\" >Emergencias e Inundaciones<\/option><option value=\"87789\" >Industrial \/ Construcci\u00f3n Civil Ligera<\/option><option value=\"87780\" >Infraestructura de transporte<\/option><option value=\"87783\" >Infraestructura Urbana<\/option><option value=\"87774\" >Miner\u00eda<\/option><option value=\"87792\" >Obras de Control Costero y Fluvial<\/option><option value=\"87777\" >Petr\u00f3leo &#038; Gas \/ Energ\u00eda<\/option><option value=\"87771\" >Protecci\u00f3n Ambiental<\/option>                            <\/select>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-12 col-lg-3\">\n                        <div class=\"form-group\">\n                            <select class=\"form-control form-control-lg select\" name=\"applications-select\" id=\"applications-select\">\n                                <option value=\"\">Applicaci\u00f3n<\/option>\n                                <option value=\"87838\" >Alambres &#038; Enrejados<\/option><option value=\"87823\" >Arquitectura y Paisajismo<\/option><option value=\"87802\" >Barreras Ac\u00fasticas y de Seguridad<\/option><option value=\"87817\" >Barreras contra la nieve y protecci\u00f3n contra la ca\u00edda de rocas<\/option><option value=\"87826\" >Control de Erosi\u00f3n<\/option><option value=\"87832\" >Drenaje de estructuras<\/option><option value=\"87847\" >Estabilizaci\u00f3n del suelo y pavimentos<\/option><option value=\"87820\" >Fabricaci\u00f3n Industrial<\/option><option value=\"87805\" >Muros de contenci\u00f3n y refuerzo del suelo<\/option><option value=\"87841\" >Obras ambientales<\/option><option value=\"87811\" >Obras Hidr\u00e1ulicas<\/option><option value=\"87835\" >Obras mar\u00edtimas<\/option><option value=\"87808\" >Redes\/Jaulas de Acuicultura<\/option><option value=\"87814\" >Refuerzo de la base<\/option><option value=\"87844\" >Soluciones para pisos de concreto, prefabricados y otros usos<\/option><option value=\"87829\" >T\u00faneles<\/option>                            <\/select>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-12 col-lg-3\"><!-- col-lg-4 -->\n                        <div class=\"form-group\">\n                            <select class=\"form-control form-control-lg select\" name=\"solutions-select\" id=\"solutions-select\">\n                                <option value=\"\">Soluci\u00f3n<\/option>\n                                <option value=\"87516\" >\u00a0A cuestas<\/option><option value=\"87546\" >\u00a0Acuicultura Marina<\/option><option value=\"87573\" >\u00a0Aplicaciones de chapa en el suelo<\/option><option value=\"87564\" >Barreras Ac\u00fasticas<\/option><option value=\"87498\" >\u00a0Barreras contra flujos de escombros y deslizamientos de tierra superficiales<\/option><option value=\"87537\" >\u00a0Barreras de nieve y protecci\u00f3n contra avalanchas<\/option><option value=\"87513\" >\u00a0Barreras de protecci\u00f3n de la fuerza<\/option><option value=\"87567\" >\u00a0Barreras de seguridad<\/option><option value=\"87492\" >Barreras Din\u00e1micas<\/option><option value=\"87612\" >\u00a0Consolidaci\u00f3n por sistemas de drenaje<\/option><option value=\"87540\" >\u00a0Consolidaci\u00f3n y refuerzo de la excavaci\u00f3n<\/option><option value=\"87507\" >\u00a0Construcci\u00f3n en cavidades<\/option><option value=\"87501\" >\u00a0Construcciones en suelo blando<\/option><option value=\"87579\" >\u00a0Deshidrataci\u00f3n<\/option><option value=\"87561\" >\u00a0Drenaje de subsuelos y pavimentos<\/option><option value=\"87555\" >\u00a0Drenaje horizontal y vertical<\/option><option value=\"87510\" >\u00a0Embarcaderos y estructuras costeras<\/option><option value=\"87552\" >\u00a0Escolleras y espigones (obras fluviales desviadas)<\/option><option value=\"87543\" >\u00a0Estructuras de contenci\u00f3n por gravedad<\/option><option value=\"87603\" >\u00a0Estructuras de contenci\u00f3n reforzadas con suelo y refuerzo de taludes<\/option><option value=\"87633\" >Final Lining<\/option><option value=\"87504\" >\u00a0Impermeabilizaci\u00f3n de embalses, lagos y canales<\/option><option value=\"87585\" >\u00a0Mitigar los obst\u00e1culos<\/option><option value=\"87624\" >\u00a0Muelles y embarcaderos<\/option><option value=\"87534\" >\u00a0Muros verticales con paneles de revestimiento de hormig\u00f3n<\/option><option value=\"87519\" >Obras de canalizaci\u00f3n<\/option><option value=\"87495\" >\u00a0Obras de drenaje vertical<\/option><option value=\"87627\" >\u00a0Praderas marinas y reconstrucci\u00f3n de arrecifes<\/option><option value=\"87591\" >\u00a0Presas de desprendimiento de rocas<\/option><option value=\"87582\" >\u00a0Presas, galer\u00edas y estructuras transversales<\/option><option value=\"87549\" >\u00a0Protecci\u00f3n de taludes<\/option><option value=\"87558\" >Protecci\u00f3n de tuber\u00edas<\/option><option value=\"87630\" >Protecci\u00f3n Longitudinal<\/option><option value=\"87600\" >\u00a0Reconstrucci\u00f3n de las dunas<\/option><option value=\"87588\" >\u00a0Red Anti Depredadores<\/option><option value=\"87531\" >\u00a0Refuerzo y soporte de la superficie<\/option><option value=\"87609\" >\u00a0Refuerzos de la capa de asfalto<\/option><option value=\"87606\" >\u00a0Refuerzos del subsuelo<\/option><option value=\"87615\" >\u00a0Revestimiento Primario<\/option><option value=\"87618\" >Rvestimiento Simple<\/option><option value=\"87576\" >\u00a0Sistemas de cobertura &#8211; Capa de cobertura del vertedero<\/option><option value=\"87522\" >\u00a0Sistemas de revestimiento &#8211; Control del caudal\/de la base<\/option><option value=\"87528\" >Soluciones para pisos de concreto, prefabricados y otros usos<\/option><option value=\"87621\" >Suelo Grapado<\/option><option value=\"87570\" >\u00a0Suelos marginales y refuerzo de residuos<\/option><option value=\"87597\" >\u00a0Tanques de red para piscicultura<\/option><option value=\"87525\" >\u00a0Tapado de sedimentos<\/option><option value=\"87594\" >\u00a0Terraplenes reforzados<\/option>                            <\/select>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-12 col-lg-3\"> <!-- order-lg-2 -->\n                        <div class=\"form-group\">\n                            <select class=\"form-control form-control-lg select\" name=\"products-select\" id=\"products-select\">\n                                <option value=\"\">Productos<\/option>\n                                <option value=\"87634\" >ACBM<\/option><option value=\"93507\" >ACBM<\/option><option value=\"87748\" >Barreras contra desprendimientos de rocas<\/option><option value=\"93480\" >Barreras contra desprendimientos de rocas<\/option><option value=\"87667\" >Barreras de Flujo de Detritos<\/option><option value=\"93468\" >Barreras de Flujo de Detritos<\/option><option value=\"87763\" >Barreras de nieve<\/option><option value=\"93597\" >Barreras de nieve<\/option><option value=\"87715\" >BioMateriales<\/option><option value=\"93504\" >BioMateriales<\/option><option value=\"87766\" >Colchon Reno\u00ae Plus<\/option><option value=\"93021\" >Colch\u00f3n Reno\u00ae Plus<\/option><option value=\"87721\" >Colchones bituminosos Sarmac<\/option><option value=\"93060\" >Colchones bituminosos Sarmac<\/option><option value=\"87679\" >Compuestos de drenaje<\/option><option value=\"93549\" >Compuestos de drenaje<\/option><option value=\"87658\" >EBS MAC<\/option><option value=\"93048\" >EBS MAC<\/option><option value=\"87697\" >Erdox Snow<\/option><option value=\"93606\" >Erdox Snow<\/option><option value=\"87652\" >FibroMac<\/option><option value=\"93567\" >FibroMac<\/option><option value=\"87724\" >FlexMac DT<\/option><option value=\"93486\" >FlexMac DT<\/option><option value=\"87709\" >Gaviones<\/option><option value=\"93015\" >Gaviones<\/option><option value=\"87637\" >Geomallas biaxiales<\/option><option value=\"93588\" >Geomallas biaxiales<\/option><option value=\"87682\" >Geomallas Monoaxiales<\/option><option value=\"93513\" >Geomallas Monoaxiales<\/option><option value=\"87673\" >Geomembranas polim\u00e9ricas<\/option><option value=\"93492\" >Geomembranas polim\u00e9ricas<\/option><option value=\"87769\" >Geotextil No Tejido<\/option><option value=\"93471\" >Geotextil No Tejido<\/option><option value=\"87742\" >Geotextiles tejidos PP\/PE<\/option><option value=\"93072\" >Geotextiles tejidos PP\/PE<\/option><option value=\"87661\" >HELLOMAC<\/option><option value=\"93579\" >HELLOMAC<\/option><option value=\"87745\" >Kikkonet<\/option><option value=\"93501\" >Kikkonet<\/option><option value=\"87736\" >Lona<\/option><option value=\"93075\" >Lona<\/option><option value=\"87643\" >MacArmour &#038; SteelGrid<\/option><option value=\"93585\" >MacArmour\u00ae &amp; SteelGrid\u00ae<\/option><option value=\"87757\" >MacGrid AR<\/option><option value=\"93525\" >MacGrid AR<\/option><option value=\"87646\" >MacLine GCL<\/option><option value=\"93594\" >MacLine GCL<\/option><option value=\"87670\" >MacMat<\/option><option value=\"93510\" >MacMat\u00ae<\/option><option value=\"87751\" >MacMat HS<\/option><option value=\"93528\" >MacMat\u00ae HS<\/option><option value=\"87712\" >MacMat R<\/option><option value=\"93057\" >MacMat\u00ae R<\/option><option value=\"87700\" >MacRes<\/option><option value=\"93558\" >MacRes<\/option><option value=\"87691\" >MacSafe<\/option><option value=\"93552\" >MacSafe\u00ae<\/option><option value=\"87754\" >MacWall<\/option><option value=\"93603\" >MacWall\u00ae<\/option><option value=\"87664\" >MacWeb<\/option><option value=\"93555\" >MacWeb\u00ae<\/option><option value=\"87694\" >Mallas<\/option><option value=\"93573\" >Mallas<\/option><option value=\"87655\" >Multi Composites<\/option><option value=\"93600\" >Multi Composites<\/option><option value=\"87727\" >Multiple Plates Culverts Technology<\/option><option value=\"93042\" >Multiple Plates Culverts Technology<\/option><option value=\"87688\" >Paneles<\/option><option value=\"93483\" >Paneles<\/option><option value=\"92970\" >Refuerzo de t\u00faneles<\/option><option value=\"87649\" >RenoMesh<\/option><option value=\"93591\" >RenoMesh<\/option><option value=\"87718\" >Road Safety Barriers<\/option><option value=\"93063\" >Road Safety Barriers<\/option><option value=\"87640\" >Soluciones de vallas de alambre soldado<\/option><option value=\"93570\" >Soluciones de vallas de alambre soldado<\/option><option value=\"87730\" >Soluciones marinas sint\u00e9ticas<\/option><option value=\"92985\" >Soluciones marinas sint\u00e9ticas<\/option><option value=\"87733\" >SubMac<\/option><option value=\"93066\" >SubMac<\/option><option value=\"87739\" >Tejido de poli\u00e9ster \/ compuesto geotextil<\/option><option value=\"93477\" >Tejido de poli\u00e9ster \/ compuesto geotextil<\/option><option value=\"87676\" >Terramesh<\/option><option value=\"93039\" >Terramesh\u00ae<\/option><option value=\"87685\" >T\u00faneles &#8211; Arco met\u00e1lico<\/option><option value=\"93498\" >T\u00faneles &#8211; Arco met\u00e1lico<\/option><option value=\"87873\" >Tunelling reinforcement<\/option><option value=\"87760\" >Wirand<\/option><option value=\"93522\" >Wirand\u00ae<\/option>                            <\/select>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-12 col-lg-3 order-lg-3 d-none hide\">\n                        <div class=\"form-group\">\n                            <select class=\"form-control form-control-lg select\" name=\"location-select\" id=\"location-select\">\n                                <option value=\"\"><\/option>\n                            <\/select>\n                        <\/div>\n                    <\/div>\n                    <!--                     <div class=\"col-12 col-lg-2\">\n                        <div class=\"form-group\">\n                            <button type=\"button\" class=\"btn-filter\" style=\"width: 100%; height: 40px;\">Filtrar<\/button>\n                        <\/div>\n                    <\/div> -->\n                <\/div>\n                <div class=\"row\">\n                    <div class=\"col-12\">\n                        <div class=\"adv-open-pan\">B\u00fasqueda Avanzada<\/div>\n                    <\/div>\n                    <div class=\"col-12 toggle-adv-options close d-none\">\n                        <div class=\"container-full\">\n                            <div class=\"row\">\n                                <div class=\"col-12 height-all\">\n                                    <label class=\"checkbox\">\n                                        <input type=\"checkbox\" name=\"full\" id=\"full\" class=\"all-type\" checked><span class=\"all\">Todos<\/span>\n                                    <\/label>\n                                <\/div>\n                                <div class=\"col-12 col-lg-3 adv-types\"><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_prodotti\" value=\"1\" > <span>Productos<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_success-stories\" value=\"1\" > <span>Casos de \u00e9xito<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_case-histories\" value=\"1\" > <span>Case Histories<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_brochures\" value=\"1\" > <span>Catalogos<\/span><\/label><br \/><\/div><div class=\"col-12 col-lg-3 adv-types\"><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_press\" value=\"1\" > <span>COMUNICADOS DE PRENSA<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_news\" value=\"1\" > <span>NOTICIAS DE LA COMPA\u00d1\u00cdA<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_article\" value=\"1\" > <span>Trabajos T\u00e9cnicos<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_wpdmpro\" value=\"1\" > <span>Otros documentos<\/span><\/label><br \/><\/div><div class=\"col-12 col-lg-3 adv-types\"><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_installation-documents\" value=\"1\" > <span>Documentos de instalaci\u00f3n<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_techical-documents\" value=\"1\" > <span>Otros documentos t\u00e9cnicos<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_webinar\" value=\"1\" > <span>Webinars<\/span><\/label><br \/><label class=\"checkbox\"><input type=\"checkbox\" name=\"find_softwares\" value=\"1\" > <span>Softwares<\/span><\/label><br \/><\/div>                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"row\">\n                    <div class=\"col-12 text-end\">\n                        <div class=\"form-group\">\n                            <button type=\"button\" class=\"btn-filter\">Filtrar<\/button>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/form>\n        <\/div>\n    <\/div>\n<\/div>\n<div id=\"search-result\" class=\"text-center\" style=\"display: none;\">\n    <!-- ?php echo __('Loading....', 'maccaferri') ? -->\n    <div class=\"loader-result text-center\"><\/div>\n<\/div>\n<script type=\"text\/javascript\">\n    (function($) {\n        let sectorsSelect = jQuery('#sectors-select');\n        let applicationsSelect = jQuery('#applications-select');\n        let solutionsSelect = jQuery('#solutions-select');\n        let productsSelect = jQuery('#products-select');\n\n        let originalApplicationsOptions = applicationsSelect.find('option').not(':first');\n        let originalSolutionsOptions = solutionsSelect.find('option').not(':first');\n        let originalProductsOptions = productsSelect.find('option').not(':first');\n\n\n        function dynamicDropdown_readAndFill(results, parent, parentId, dropDownInstance) {\n            let url = \"https:\/\/www.maccaferri.com\/latam\/wp-admin\/admin-ajax.php?action=maccaferri_search_dropdown&results=\" + results + \"&parent=\" + parent + \"&parentId=\" + parentId;\n            \/\/alert(url);\n            jQuery.ajax({\n                url: url,\n                type: \"GET\",\n                dataType: \"json\",\n                success: function(response) {\n                    if (response.status == 'success') {\n                        var res = response.data;\n                        console.log(res);\n                        $.each(res, function(i, v) {\n                            console.log(v);\n                            dropDownInstance.append(\n                                jQuery('<option><\/option>').val(v.ID).html(v.title)\n                            );\n                        });\n                    }\n                }\n            });\n        }\n\n        function dynamicDropdown_handleSectors(sectorId) {\n\n            \/\/Clear applications, solutions and products\n            applicationsSelect.find('option').not(':first').remove();\n            solutionsSelect.find('option').not(':first').remove();\n            productsSelect.find('option').not(':first').remove();\n            if (sectorId == '') {\n                \/\/Restore original select options\n                applicationsSelect.append(originalApplicationsOptions);\n                solutionsSelect.append(originalSolutionsOptions);\n                productsSelect.append(originalProductsOptions);\n            } else {\n                \/\/Get all applications, solutions and products with the given sector id\n                dynamicDropdown_readAndFill(\"applications\", \"sector\", sectorId, applicationsSelect);\n                dynamicDropdown_readAndFill(\"solutions\", \"sector\", sectorId, solutionsSelect);\n                dynamicDropdown_readAndFill(\"products\", \"sector\", sectorId, productsSelect);\n            }\n        }\n\n        function dynamicDropdown_handleApplications(applicationId) {\n            \/\/Clear solutions and products\n            solutionsSelect.find('option').not(':first').remove();\n            productsSelect.find('option').not(':first').remove();\n            if (applicationId == '') {\n                \/\/Call parent\n                let sectorId = sectorsSelect.val();\n                dynamicDropdown_handleSectors(sectorId);\n            } else {\n                \/\/Get all solutions and products with the given sector id\n                dynamicDropdown_readAndFill(\"solutions\", \"application\", applicationId, solutionsSelect);\n                dynamicDropdown_readAndFill(\"products\", \"application\", applicationId, productsSelect);\n            }\n        }\n\n        function dynamicDropdown_handleSolutions(solutionId) {\n            \/\/Clear products\n            productsSelect.find('option').not(':first').remove();\n            if (solutionId == '') {\n                \/\/Call parent\n                let applicationId = applicationsSelect.val();\n                dynamicDropdown_handleApplications(applicationId);\n            } else {\n                \/\/Get all products with the given sector id\n                dynamicDropdown_readAndFill(\"products\", \"solution\", solutionId, productsSelect);\n            }\n        }\n\n        sectorsSelect.change(function(e) {\n            e.preventDefault();\n            \/\/Read sectors id\n            let sectorId = this.value;\n            dynamicDropdown_handleSectors(sectorId);\n        });\n        applicationsSelect.change(function(e) {\n            e.preventDefault();\n            \/\/Read applications id\n            let applicationId = this.value;\n            dynamicDropdown_handleApplications(applicationId);\n        });\n        solutionsSelect.change(function(e) {\n            e.preventDefault();\n            \/\/Read solutions id\n            let solutionId = this.value;\n            dynamicDropdown_handleSolutions(solutionId);\n        });\n\n        function checkFilter() {\n            var check = false;\n            $('.toggle-adv-options input[type=checkbox]').each(function() {\n                if ($(this).is(':checked')) {\n                    check = true;\n                }\n            });\n\n            if (check) {\n                $('.adv-open-pan').prepend('<span class=\"filter-on\" style=\"position: absolute; margin-left: -21px; margin-top: 4px;\"><span class=\"material-symbols-outlined\" style=\"font-size: 19px;\">filter_alt<\/span><\/span>');\n            } else {\n                $('.filter-on').remove();\n            }\n        }\n\n        checkFilter();\n        $('.adv-open-pan').click(function(e) {\n            e.preventDefault();\n            if ($('.toggle-adv-options').hasClass('close')) {\n                $('.toggle-adv-options').hide().removeClass('d-none').removeClass('close').slideDown();\n            } else {\n                $('.toggle-adv-options').addClass('close').slideUp('fast', function() {\n                    $(this).addClass('d-none');\n                });\n                \/\/ $('.adv-types input, .all-type').prop('checked', false);\n            }\n        });\n        $('.all-type').change(function(e) {\n            e.preventDefault();\n            if ($(this).is(':checked')) {\n                $('.adv-types input').prop('checked', true);\n            } else {\n                $('.adv-types input').prop('checked', false);\n            }\n            checkFilter();\n        });\n        $('.adv-types input').change(function(e) {\n            e.preventDefault();\n            if (!$(this).is(':checked')) {\n                $('.all-type').prop('checked', false);\n            }\n            if (checkAdv()) {\n                $('.all-type').prop('checked', true);\n            }\n            checkFilter();\n        });\n        var checkAdv = function() {\n            var check = true;\n            $('.adv-types input').each(function(index) {\n                if (!$(this).is(':checked')) {\n                    check = false;\n                }\n            });\n            return check;\n        };\n        $('.adv-open-pan').click(function() {\n            $(this).toggleClass('close');\n        });\n\n        function runSearch() {\n            let dataForm = $('#main-search-form').serialize();\n                            $('#main-search-form')[0].submit();\n                    }\n\n\n        $('#main-search-form').submit(function(e) {\n            e.preventDefault();\n            $('input.category-link').val('');\n            runSearch();\n            return false;\n        });\n\n        $('.btn-filter, .submit-search').click(function(e) {\n            e.preventDefault();\n            $('input.category-link').val('');\n            runSearch();\n        });\n\n            })(jQuery);\n<\/script><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f8f9fa\"><div class=\"wp-block-mac-container-block box-container\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-banner-title-cta  box-container block-cta\" style=\"background:#015E6F\"><div class=\"container box-container\"><div class=\"row\"><div class=\"col-2 col-sm-2 col-md-2 col-lg-2 col-xl-2 col-xxl-2\"><div class=\"box-image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/11\/img-banner-software.png\" alt=\"Image\"\/><\/div><\/div><div class=\"col-7 col-sm-7 col-md-7 col-lg-7 col-xl-7 col-xxl-7\"><div class=\"banner-box-txt\" style=\"text-align:default\"><h4 class=\"title\">USE NUESTROS OBJECTOS BIM PARA PROYECTAR EL FUTURO<\/h4><\/div><\/div><div class=\"col-3 col-sm-3 col-md-3 col-lg-3 col-xl-3 col-xxl-3\"><div class=\"button-box-txt\"><a href=\"https:\/\/www.maccaferri.com\/latam\/biblioteca-de-objetos-bim\" target=\"_blank\" class=\"buttonurl\" rel=\"noopener\"><span class=\"buttontext\">ir a la biblioteca<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-mac-h2-title-block block-txt-container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><h2 style=\"color:#212429;text-align:none\">OBJECTOS MACCAFERRI BIM<\/h2><\/div><\/div><\/div><div class=\"wp-block-mac-container-block box-container\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-banner-title-cta  box-container block-cta\" style=\"background:#015E6F\"><div class=\"container box-container\"><div class=\"row\"><div class=\"col-2 col-sm-2 col-md-2 col-lg-2 col-xl-2 col-xxl-2\"><div class=\"box-image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/img-banner-software.png\" alt=\"Image\"\/><\/div><\/div><div class=\"col-7 col-sm-7 col-md-7 col-lg-7 col-xl-7 col-xxl-7\"><div class=\"banner-box-txt\" style=\"text-align:default\"><h4 class=\"title\">USE NUESTROS OBJECTOS BIM PARA PROYECTAR EL FUTURO<\/h4><\/div><\/div><div class=\"col-3 col-sm-3 col-md-3 col-lg-3 col-xl-3 col-xxl-3\"><div class=\"button-box-txt\"><a href=\"https:\/\/www.maccaferri.com\/latam\/biblioteca-de-objetos-bim\" target=\"_blank\" class=\"buttonurl\" rel=\"noopener\"><span class=\"buttontext\">ir a la biblioteca<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-title-cta-block container box-container orange\" style=\"background:#ffffff\"><div class=\"row\"><div class=\"col-9 title-box-txt\"><h2 class=\"wp-block-mac-title-cta-block orange\" style=\"color:#212429;text-align:left\">Editorial de Maccaferri<\/h2><\/div><div class=\"col-3 button-box-txt\"><a href=\"latam\/search?c=news\" class=\"buttonurl\" rel=\"noopener\"><span class=\"buttontext\">Todos los Editoriales<\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-container-block box-container\"><div class=\"container\"><h4 class=\"title-article\"><\/h4><div class=\"row\"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"wp-block-mac-card-new-block block-latest-news-container\"><div class=\"card\"><div class=\"content-images\"><img decoding=\"async\" class=\"box-image\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/10\/An-engineering-marvel-in-the-midst-of-the-Himalaya-1.png\" alt=\"Private: An engineering marvel in the midst of the Himalaya_OLD\" \/><\/div><div class=\"card-body\"><h6>Private: An engineering marvel in the midst of the Himalaya_OLD<\/h6><span class=\"abstract\">The 100th operational airport in India required retention megastructures up to 74m high<\/span><a href=\"https:\/\/www.maccaferri.com\/latam\/?p=2325\" class=\"cta\" rel=\"noopener\">Lea ahora\n                        <span class=\"text\" value=\"\" \/>\n                        <\/a><div data-post-id=\"2325\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f8f9fa\"><div class=\"box-container title-box-txt\"><h2>Descubra nuestros productos y soluciones<\/h2><\/div><div class=\"wp-container wp-block-column carousel-discover-products hbox\"><div class=\"carousel-discover-products container\"><div class=\"row\"><div id=\"carouseldiscoverproducts\" class=\"carousel slide\" data-bs-ride=\"carousel\"><ol class=\"carousel-indicators\"><li data-bs-target=\"#carouseldiscoverproducts\" data-bs-slide-to=\"0\" class=\"active\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouseldiscoverproducts\" data-bs-slide-to=\"1\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouseldiscoverproducts\" data-bs-slide-to=\"2\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouseldiscoverproducts\" data-bs-slide-to=\"3\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouseldiscoverproducts\" data-bs-slide-to=\"4\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><\/ol><a class=\"carousel-control-prev w-aut\" href=\"#carouseldiscoverproducts\" role=\"button\" data-bs-slide=\"prev\">\n                     <span class=\"carousel-control-prev-icon\" aria-hidden=\"true\"><\/span>\n                  <\/a><a class=\"carousel-control-next w-aut\" href=\"#carouseldiscoverproducts\" role=\"button\" data-bs-slide=\"next\">\n                    <span class=\"carousel-control-next-icon\" aria-hidden=\"true\"><\/span>\n                  <\/a> <div class=\"carousel-inner container box-container\" role=\"listbox\"><div class=\"carousel-item active\"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-brochure.png\"> <\/div><div class=\"subtitle\">Erdox Snow<\/div><p>Las estructuras de nieve ErdoX de Maccaferri son medidas de protecci\u00f3n que se colocan en las zonas de inicio de los aludes para estabilizar la <\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/productos\/erdox-snow-2\/\">Visualizar <\/a><div data-post-id=\"93606\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-brochure.png\"> <\/div><div class=\"subtitle\">MacWall\u00ae<\/div><p>Con un proceso constructivo r\u00e1pido y sencillo, MacWall\u00ae ofrece a arquitectos e ingenieros una soluci\u00f3n vers\u00e1til que combina funcionalidad y atractivo <\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/productos\/macwall-2\/\">Visualizar <\/a><div data-post-id=\"93603\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-brochure.png\"> <\/div><div class=\"subtitle\">Multi Composites<\/div><p><\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/productos\/multi-composites-2\/\">Visualizar <\/a><div data-post-id=\"93600\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-brochure.png\"> <\/div><div class=\"subtitle\">Barreras de nieve<\/div><p>Est\u00e1n dise\u00f1adas para estabilizar la capa de nieve en la zona de inicio de la avalancha potencial, evitando as\u00ed que se desencadene. El volumen de nieve<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/productos\/barreras-de-nieve-2\/\">Visualizar <\/a><div data-post-id=\"93597\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-3 col-xl-3 col-xxl-3\" style=\"float:inherit\"><div class=\"card\"><div class=\"box-images\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/11\/icon-brochure.png\"> <\/div><div class=\"subtitle\">MacLine GCL<\/div><p>Geocompuestos de Arcilla de Alto Desempe\u00f1o para Barreras de Baja PermeabilidadLos Geo-Clay Liners (GCL) son barreras compuestas creadas media<\/p><a class=\"cta\" href=\"https:\/\/www.maccaferri.com\/latam\/productos\/macline-gcl-2\/\">Visualizar <\/a><div data-post-id=\"93594\" class=\"star \" title=\"A\u00f1adir a la lista de deseos\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-editor-grid-block-image-transparent container-media box-container\"><div class=\"row\"><div class=\"col-12 col-lg-5 col-xl-5 col-xxl-5 title-box-txt\" style=\"text-align:default\"><h3 class=\"title\" style=\"color:#004857\">Nuestra experiencia proviene de nuestro personal<\/h3><p class=\"description\" style=\"color:#004857\">Representamos un socio ganador para el complejo mundo de la construcci\u00f3n civil e industrial. Gracias a una amplia gama, nuestros productos son la soluci\u00f3n a las diversas exigencias y demandas t\u00e9cnicas del sector: desde drenaje, protecci\u00f3n y control de erosi\u00f3n hasta barreras de presas de relaves, valorando la reducci\u00f3n de recursos naturales, con ahorro energ\u00e9tico y recursos financieros.g comfort, from steam control to issues concerning.<\/p><div class=\"button-box-txt\" style=\"text-align:default\"><a href=\"https:\/\/www.maccaferri.com\/latam\/contactenos\" class=\"buttonurl\" rel=\"noopener\" style=\"background:#3DA3A7\"><span class=\"buttontext\">Con\u00f3cenos<\/span><\/a><\/div><\/div><div class=\"col-12 offset-lg-1 offset-xl-1 offset-xxl-1 col-lg-6 col-xl-6 col-xxl-6 text-end\"><div class=\"box-image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2023\/05\/Knowledge-Centre-16.jpg\" alt=\"Image\"\/><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-1413","page","type-page","status-publish","hentry"],"acf":{"uuid_products":"","product-documents":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Centro de conocimiento - Maccaferri Latam<\/title>\n<meta name=\"description\" content=\"Centro de conocimiento USE NUESTROS SOFTWARESPARA PROYECTAR EL FUTUROSecci\u00f3n de Softwares OBJECTOS MACCAFERRI BIM USE NUESTROS OBJECTOS BIM PARA PROYECTAR\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro de conocimiento - Maccaferri Latam\" \/>\n<meta property=\"og:description\" content=\"Centro de conocimiento USE NUESTROS SOFTWARESPARA PROYECTAR EL FUTUROSecci\u00f3n de Softwares OBJECTOS MACCAFERRI BIM USE NUESTROS OBJECTOS BIM PARA PROYECTAR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Maccaferri Latam\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T16:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/centro-de-conocimiento\\\/\",\"url\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/centro-de-conocimiento\\\/\",\"name\":\"Centro de conocimiento - Maccaferri Latam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/centro-de-conocimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/centro-de-conocimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/test-h1-bg.jpg\",\"datePublished\":\"2022-07-29T10:02:56+00:00\",\"dateModified\":\"2025-02-06T16:52:58+00:00\",\"description\":\"Centro de conocimiento USE NUESTROS SOFTWARESPARA PROYECTAR EL FUTUROSecci\u00f3n de Softwares OBJECTOS MACCAFERRI BIM USE NUESTROS OBJECTOS BIM PARA PROYECTAR\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/centro-de-conocimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/centro-de-conocimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/test-h1-bg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/test-h1-bg.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/#website\",\"url\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/\",\"name\":\"Maccaferri Latam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/#organization\",\"name\":\"Maccaferri Latam\",\"url\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-maccaferri.png\",\"contentUrl\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-maccaferri.png\",\"width\":152,\"height\":32,\"caption\":\"Maccaferri Latam\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maccaferri.com\\\/latam\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Centro de conocimiento - Maccaferri Latam","description":"Centro de conocimiento USE NUESTROS SOFTWARESPARA PROYECTAR EL FUTUROSecci\u00f3n de Softwares OBJECTOS MACCAFERRI BIM USE NUESTROS OBJECTOS BIM PARA PROYECTAR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Centro de conocimiento - Maccaferri Latam","og_description":"Centro de conocimiento USE NUESTROS SOFTWARESPARA PROYECTAR EL FUTUROSecci\u00f3n de Softwares OBJECTOS MACCAFERRI BIM USE NUESTROS OBJECTOS BIM PARA PROYECTAR","og_url":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/","og_site_name":"Maccaferri Latam","article_modified_time":"2025-02-06T16:52:58+00:00","og_image":[{"url":"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/","url":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/","name":"Centro de conocimiento - Maccaferri Latam","isPartOf":{"@id":"https:\/\/www.maccaferri.com\/latam\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg","datePublished":"2022-07-29T10:02:56+00:00","dateModified":"2025-02-06T16:52:58+00:00","description":"Centro de conocimiento USE NUESTROS SOFTWARESPARA PROYECTAR EL FUTUROSecci\u00f3n de Softwares OBJECTOS MACCAFERRI BIM USE NUESTROS OBJECTOS BIM PARA PROYECTAR","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.maccaferri.com\/latam\/centro-de-conocimiento\/#primaryimage","url":"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg","contentUrl":"https:\/\/www.maccaferri.com\/latam\/\/wp-content\/uploads\/2022\/09\/test-h1-bg.jpg"},{"@type":"WebSite","@id":"https:\/\/www.maccaferri.com\/latam\/#website","url":"https:\/\/www.maccaferri.com\/latam\/","name":"Maccaferri Latam","description":"","publisher":{"@id":"https:\/\/www.maccaferri.com\/latam\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maccaferri.com\/latam\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.maccaferri.com\/latam\/#organization","name":"Maccaferri Latam","url":"https:\/\/www.maccaferri.com\/latam\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.maccaferri.com\/latam\/#\/schema\/logo\/image\/","url":"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/07\/logo-maccaferri.png","contentUrl":"https:\/\/www.maccaferri.com\/latam\/wp-content\/uploads\/2022\/07\/logo-maccaferri.png","width":152,"height":32,"caption":"Maccaferri Latam"},"image":{"@id":"https:\/\/www.maccaferri.com\/latam\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/pages\/1413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/comments?post=1413"}],"version-history":[{"count":124,"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/pages\/1413\/revisions"}],"predecessor-version":[{"id":63031,"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/pages\/1413\/revisions\/63031"}],"wp:attachment":[{"href":"https:\/\/www.maccaferri.com\/latam\/wp-json\/wp\/v2\/media?parent=1413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}