{"id":98953,"date":"2025-03-20T14:42:45","date_gmt":"2025-03-20T13:42:45","guid":{"rendered":"https:\/\/www.maccaferri.com\/br\/?post_type=webinar&#038;p=98953"},"modified":"2025-06-02T15:47:32","modified_gmt":"2025-06-02T13:47:32","slug":"preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design","status":"publish","type":"webinar","link":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/","title":{"rendered":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design"},"content":{"rendered":"<h4>27\/03\/2025<\/h4><div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/wp-content\/uploads\/2023\/02\/english.png\" alt=\"\" class=\"wp-image-8550\"\/><\/figure><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/wp-content\/uploads\/2023\/02\/italian.png\" alt=\"\" class=\"wp-image-8553\"\/><\/figure><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/wp-content\/uploads\/2023\/02\/spanish.png\" alt=\"\" class=\"wp-image-8554\"\/><\/figure><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h5>Preassembled drainage trenches: GabioDrain, the new solution for optimized design\n<\/h5>\n\n<p class=\"wp-block-paragraph\">Traditional drainage trench construction is time-consuming, material-intensive, and costly. But what if there was a more efficient way?<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\"><strong>GabioDrain <\/strong>is an innovative <strong>preassembled <\/strong>solution for <strong>drainage trenches<\/strong>&nbsp;that simplifies installation, reduces material usage, and optimizes project costs. Designed to enhance efficiency, it provides a <strong>ready-to-use solution<\/strong>&nbsp;that cuts down on environmental impact while ensuring high drainage performance.<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">Join us for an exclusive <strong>webinar on March 27<\/strong>, where our experts will:<\/p>\n\n<p class=\"wp-block-paragraph\">\u2705 Present the<strong>\u00a0different GabioDrain solutions<\/strong>\u00a0and how to select the most suitable one for your project.<br>\u2705 <strong>Compare GabioDrain with traditional drainage trenches<\/strong>, based on tests, studies, and experimental trials.<br>\u2705 Share key\u00a0insights on our<strong>\u00a0new design tool<\/strong>, offering practical tips to optimize your\u00a0drainage solutions.<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">&nbsp;Don&#8217;t miss this opportunity the new approach to drainage trench design, register now!<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h5>Trincee Drenanti: GabioDrain, la nuova soluzione preassemblata per un design ottimizzato\n<\/h5>\n\n<p class=\"wp-block-paragraph\">La costruzione tradizionale delle trincee drenanti \u00e8 un processo lungo, costoso e dispendioso in termini di materiali. Ma se esistesse un modo pi\u00f9 efficiente?<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\"><strong>GabioDrain<\/strong>&nbsp;\u00e8 una <strong>soluzione preassemblata <\/strong>e&nbsp;innovativa, progettata per semplificare la costruzione delle <strong>trincee drenanti<\/strong>,ridurre il consumo di materiali e ottimizzare i costi di progetto. Grazie al suo design efficiente, offre una soluzione <strong>pronta all\u2019uso<\/strong>&nbsp;che riduce l\u2019impatto ambientale garantendo al contempo elevate prestazioni di drenaggio.<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">Partecipa al nostro esclusivo <strong>webinar del 27 marzo<\/strong>, dove i nostri esperti:<\/p>\n\n<p class=\"wp-block-paragraph\">\u2705 Presenterannole <strong>diverse soluzioni GabioDrain<\/strong>&nbsp;e ti guideranno nella scelta della pi\u00f9 adatta al tuo progetto.<br>\u2705 <strong>Confronteranno GabioDrain con le trincee drenanti tradizionali<\/strong>, sulla base di test, studi e prove sperimentali.<br>\u2705 Condivideranno suggerimenti sul nostro <strong>nuovo tool di design<\/strong>, offrendo consigli pratici per ottimizzare le tue soluzioni di drenaggio.<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">Non perdere l\u2019opportunit\u00e0 di scoprire il nuovo approccio alla progettazione delle trincee drenanti. Iscriviti ora!<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\"><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h5>Zanjas de drenaje pre-ensembladas: GabioDrain, la nueva soluci\u00f3n para un dise\u00f1o optimizado\n<\/h5>\n\n<p class=\"wp-block-paragraph\">La construcci\u00f3n tradicional de zanjas de drenaje requiere mucho tiempo, material y es costosa. Pero, \u00bfy si hubiera una forma m\u00e1s eficiente?<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\"><strong>GabioDrain <\/strong>es una solucion para <strong>zanjas de drenaje<\/strong> <strong>pre-ensembladas<\/strong>&nbsp;que simplifica la instalaci\u00f3n, reduce el uso de materiales y optimiza los costes del proyecto. Dise\u00f1ado para mejorar la eficiencia, proporciona una<strong>&nbsp;soluci\u00f3n lista para ser utilizada<\/strong>&nbsp;que reduce el impacto ambiental garantizando al mismo tiempo un alto rendimiento de drenaje.<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">\u00danase a nosotros en un <strong>seminario web<\/strong>&nbsp;exclusivo el<strong>&nbsp;27 de marzo<\/strong>, en el que nuestros expertos:<\/p>\n\n<p class=\"wp-block-paragraph\">\u2705 Presentar\u00e1n las<strong>&nbsp;diferentes soluciones GabioDrain <\/strong>y c\u00f3mo seleccionar la m\u00e1s adecuada para su proyecto.<\/p>\n\n<p class=\"wp-block-paragraph\">\u2705 <strong>Comparar\u00e1n GabioDrain con las zanjas de drenaje tradicionales<\/strong>, bas\u00e1ndose en pruebas, estudios y ensayos experimentales.<\/p>\n\n<p class=\"wp-block-paragraph\">\u2705Compartir\u00e1 informaci\u00f3n clave sobre nuestra <strong>nueva herramienta de dise\u00f1o<\/strong>, ofreciendo consejos pr\u00e1cticos para optimizar sus soluciones de drenaje.<\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">No se pierda esta oportunidad de descubrir el nuevo enfoque para el dise\u00f1o de zanjas de drenaje, \u00a1reg\u00edstrese ahora!<\/p><\/div><\/div><\/div><\/div><\/div><\/div><p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Watch the webinar in English, Italian or Spanish!<\/p>\n","protected":false},"featured_media":99012,"parent":0,"menu_order":0,"template":"","webinar-category":[],"webinar-tag":[],"class_list":["post-98953","webinar","type-webinar","status-publish","has-post-thumbnail","hentry"],"acf":{"session_avaible":[{"orario_di_inizio":"08:30:00","orario_di_fine":"09:30:00","fuso_orario":"UTC +2","lingua":"English","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-live-eng\/"},{"orario_di_inizio":"11:30:00","orario_di_fine":"12:30:00","fuso_orario":"UTC +2","lingua":"Italiano","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-live-ita\/"},{"orario_di_inizio":"03:30:00","orario_di_fine":"04:30:00","fuso_orario":"UTC +2","lingua":"English","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-live-2-eng\/"},{"orario_di_inizio":"05:00:00","orario_di_fine":"06:00:00","fuso_orario":"UTC +2","lingua":"Espanol","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-live-esp\/"},{"orario_di_inizio":"06:00:00","orario_di_fine":"07:00:00","fuso_orario":"UTC +2","lingua":"Italiano","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-rec-ita\/"},{"orario_di_inizio":"09:00:00","orario_di_fine":"10:00:00","fuso_orario":"UTC +2","lingua":"English","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-recorded-eng\/"},{"orario_di_inizio":"11:00:00","orario_di_fine":"12:00:00","fuso_orario":"UTC +2","lingua":"Espanol","register_to_session":"https:\/\/www2.maccaferri.com\/webinar-gabiodrain-rec-esp\/"}],"webinar_file_download":"https:\/\/www.maccaferri.com\/webinar-preassembled-drainage-trenches\/","prodotto_associato":"","data_webinar":"2025-03-27 23:30:00","post_public":false,"icon_webinar":2505,"speakers":[3207]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Maccaferri Brasil<\/title>\n<meta name=\"description\" content=\"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Watch the webinar in English, Italian or Spanish!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preassembled drainage trenches: GabioDrain, the new solution for optimized design\" \/>\n<meta property=\"og:description\" content=\"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Watch the webinar in English, Italian or Spanish!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/\" \/>\n<meta property=\"og:site_name\" content=\"Maccaferri Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T13:47:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2025\/03\/Header-webinar-Preassembled-drainage-trenches_2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1915\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Maccaferri Brasil","description":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Watch the webinar in English, Italian or Spanish!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/","og_locale":"pt_BR","og_type":"article","og_title":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design","og_description":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Watch the webinar in English, Italian or Spanish!","og_url":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/","og_site_name":"Maccaferri Brasil","article_modified_time":"2025-06-02T13:47:32+00:00","og_image":[{"width":1915,"height":530,"url":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2025\/03\/Header-webinar-Preassembled-drainage-trenches_2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/","url":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/","name":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Maccaferri Brasil","isPartOf":{"@id":"https:\/\/www.maccaferri.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/#primaryimage"},"image":{"@id":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2025\/03\/Header-webinar-Preassembled-drainage-trenches_2-1.jpg","datePublished":"2025-03-20T13:42:45+00:00","dateModified":"2025-06-02T13:47:32+00:00","description":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design - Watch the webinar in English, Italian or Spanish!","breadcrumb":{"@id":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/#primaryimage","url":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2025\/03\/Header-webinar-Preassembled-drainage-trenches_2-1.jpg","contentUrl":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2025\/03\/Header-webinar-Preassembled-drainage-trenches_2-1.jpg","width":1915,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.maccaferri.com\/br\/webinar\/preassembled-drainage-trenches-gabiodrain-the-new-solution-for-optimized-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.maccaferri.com\/br\/"},{"@type":"ListItem","position":2,"name":"Webinar","item":"https:\/\/www.maccaferri.com\/br\/webinar\/"},{"@type":"ListItem","position":3,"name":"Preassembled drainage trenches: GabioDrain, the new solution for optimized design"}]},{"@type":"WebSite","@id":"https:\/\/www.maccaferri.com\/br\/#website","url":"https:\/\/www.maccaferri.com\/br\/","name":"Maccaferri Brasil","description":"","publisher":{"@id":"https:\/\/www.maccaferri.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maccaferri.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.maccaferri.com\/br\/#organization","name":"Maccaferri do Brasil","alternateName":"Maccaferri","url":"https:\/\/www.maccaferri.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.maccaferri.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/07\/logo-maccaferri.png","contentUrl":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/07\/logo-maccaferri.png","width":152,"height":32,"caption":"Maccaferri do Brasil"},"image":{"@id":"https:\/\/www.maccaferri.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/webinar\/98953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/webinar"}],"about":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/types\/webinar"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/speakers\/3207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/media\/99012"}],"wp:attachment":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/media?parent=98953"}],"wp:term":[{"taxonomy":"webinar-category","embeddable":true,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/webinar-category?post=98953"},{"taxonomy":"webinar-tag","embeddable":true,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/webinar-tag?post=98953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}