{"id":86289,"date":"2022-07-28T15:26:07","date_gmt":"2022-07-28T13:26:07","guid":{"rendered":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/"},"modified":"2025-10-30T21:50:28","modified_gmt":"2025-10-30T20:50:28","slug":"sobre-nos","status":"publish","type":"page","link":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/","title":{"rendered":"Perguntas frequentes"},"content":{"rendered":"<div class=\"wp-block-mac-slider-hero-page-block hero-slider\"><div id=\"hero47\" class=\"carousel slide\" data-bs-ride=\"true\"><div class=\"carousel-inner\"><div class=\"carousel-item active\"><div class=\"hero\"><div class=\"gts__picture\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg\" style=\"display:none\"\/><div class=\"gts__picture__image\" style=\"background-image:url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg)\"><\/div><\/div><div class=\"container box-container\"><div class=\"row\"><div class=\"col-12 col-lg-6 col-xl-6 col-xxl-6\"><p><span class=\"hero-index\" style=\"display:none\">0<\/span><\/p><h6 class=\"hero-abstract-container\"><span class=\"hero-abstract\">Sobre N\u00f3s<\/span><\/h6><h2 class=\"hero-text-container\"><span class=\"hero-text\">Sustentabilidade ambiental <br>movem as nossas solu\u00e7\u00f5es<\/span><\/h2><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-mac-container-block box-container\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"container content-paragraph box-container\"><div class=\"row\"><div class=\"col-12 col-lg-12 col-xl-12 col-xxl-12\"><div class=\"content-txt\"><p>&nbsp;<\/p>\n<p>H\u00e1 <strong>mais de 140 anos<\/strong>, como l\u00edder internacional de solu\u00e7\u00f5es avan\u00e7adas para os mercados de constru\u00e7\u00e3o civil, geot\u00e9cnica e ambiental. Concebemos solu\u00e7\u00f5es <strong>avan\u00e7adas para o mercado<\/strong>, <strong>duradouras<\/strong> e <strong>ecol\u00f3gicas<\/strong>, desde muros de conten\u00e7\u00e3o at\u00e9 obras hidr\u00e1ulicas e desde sistemas de mitiga\u00e7\u00e3o de quedas de rochas at\u00e9 o refor\u00e7o do solo.<\/p>\n<p>&nbsp;<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#004857\"><div class=\"wp-block-mac-title-cta-two-block container box-container\" style=\"background:#004857\"><div class=\"row\"><div class=\"col-12 col-lg-5 col-xl-5 col-xxl-5 title-box-txt\"><H2 class=\"wp-block-mac-title-cta-two-block\" style=\"color:#A7C8CB\">Vis\u00e3o<br>&amp; Miss\u00e3o<\/H2><\/div><div class=\"col-12 offset-lg-1 offset-xl-1 offset-xxl-1 col-lg-6 col-xl-6 col-xxl-6 title-box-txt\"><div style=\"text-align:right\"><p class=\"wp-block-mac-title-cta-two-block\" style=\"color:#FFFFFF\">Na segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente a paisagem da engenharia civil. Ainda hoje a estamos mudando. Trabalhamos todos os dias para encontrar solu\u00e7\u00f5es melhores e sustent\u00e1veis para nossas partes interessadas em todos os graus de latitude e longitude, seguindo lealmente nossa vis\u00e3o e nossos pilares de miss\u00e3o.<\/p><\/div><div style=\"text-align:right\"><a href=\"https:\/\/www.maccaferri.com\/br\/vision-mission\/\" class=\"buttonurl\" rel=\"noopener\"><span class=\"buttontext\">Conhe\u00e7a mais<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-h2-title-block block-txt-container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><h2 style=\"color:#212429;text-align:left\">Maccaferri em um clique<\/h2><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-container-block box-container\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-card-height-block block-card-height-block-container\"><div class=\"card\"><div class=\"content-images\"><img decoding=\"async\" class=\"box-image\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/05\/Inauguration_Balkans_1-min-5.jpg\" alt=\"Image Stories\"\/><\/div><div class=\"card-body\"><h6 class=\"wp-block-mac-card-height-block\" style=\"color:#212429\"><strong>MACCAFERRI OPENED A NEW HUB IN ALBANIA TO CREATE THE LARGEST PRODUCTION FACILITY IN EUROPE<\/strong><br><\/h6><span class=\"abstract\" style=\"color:#212429\"><em>With an investment of over 4M \u20ac, the new plant will become a center of excellence for the development of cutting-edge production technologies<\/em>.<\/span><a href=\"https:\/\/youtu.be\/6_rJkzIYY50\" target=\"_blank\" class=\"cta\" rel=\"noopener\"><span class=\"text\" style=\"color:#004857\">Watch the video<\/span><\/a><div class=\"star\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-mac-number-block-percent-decimal aligncenter number-container-decimal fadeoutdiv\"><p class=\"keyfactor fadeoutdiv\">PA\u00cdSES ATENDIDOS<\/p><p class=\"value boxcounter number fadeoutdiv\" number=\"130\">130<\/p><p class=\"percent fadeoutdiv\">+<\/p><div class=\"description fadeoutdiv\"><p class=\"description\">Somos uma empresa multinacional com uma experi\u00eancia mundial<\/p><\/div><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-number-block-percent-decimal number-container-decimal fadeoutdiv\"><p class=\"keyfactor fadeoutdiv\">ANOS DE HIST\u00d3RIA<\/p><p class=\"value boxcounter number fadeoutdiv\" number=\"144\">144<\/p><p class=\"percent fadeoutdiv\"><\/p><div class=\"description fadeoutdiv\"><p class=\"description\">Na segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente a paisagem da engenharia civil.<\/p><\/div><\/div>\n\n<div class=\"wp-block-mac-card-height-block block-card-height-block-container\"><div class=\"card\"><div class=\"content-images\"><img decoding=\"async\" class=\"box-image\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/12\/Maccaferri-Philippines_Anniversary.png\" alt=\"Image Stories\"\/><\/div><div class=\"card-body\"><h6 class=\"wp-block-mac-card-height-block\" style=\"color:#212429\">MACCAFERRI PHILIPPINES 20th ANNIVERSARY<\/h6><span class=\"abstract\" style=\"color:#212429\">Happy 20th-anniversary Maccaferri Philippines.<br>Mabuhay Maccaferri Philippines!<\/span><a href=\"https:\/\/www.youtube.com\/watch?v=0v3TWPk2iSQ\" target=\"_blank\" class=\"cta\" rel=\"noopener\"><span class=\"text\" style=\"color:#004857\">Watch the video<\/span><\/a><div class=\"star\"><span class=\"material-symbols-rounded starrate\">star<\/span><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-banner-blockquote container-fluid\" style=\"background:#ed791d\"><div class=\"row\"><div class=\"col\"><div class=\"gts__picture\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/06\/cattura-ape-1-3.png\" style=\"display:none\"\/><div class=\"gts__picture__image\" style=\"background-image:url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/06\/cattura-ape-1-3.png)\"><\/div><\/div><div class=\"container\"><div class=\"row\"><div class=\"col title-box-txt\"><div style=\"text-align:left\"><blockquote style=\"color:#FFFFFF\"><p class=\"wp-block-mac-banner-blockquote\" style=\"color:#FFFFFF\">&#8220;Ao cultivar o mundo de amanh\u00e3, harmonizando a vida e a natureza atrav\u00e9s de solu\u00e7\u00f5es inovadoras, Maccaferri busca a excel\u00eancia e a melhoria cont\u00ednua&#8221;.<\/p><\/blockquote><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-mac-number-block-percent-decimal aligncenter number-container-decimal fadeoutdiv\"><p class=\"keyfactor fadeoutdiv\">FUNCION\u00c1RIOS<\/p><p class=\"value boxcounter number fadeoutdiv\" number=\"3500\">3500<\/p><p class=\"percent fadeoutdiv\">+<\/p><div class=\"description fadeoutdiv\"><p class=\"description\">Somos uma fam\u00edlia com mais de 3500 pessoas trabalhando ao redor do mundo<\/p><\/div><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\" style=\"font-style:normal;font-weight:600\"><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-h2-title-block block-txt-container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><h2 style=\"color:#212429;text-align:left\">Assista agora ao nosso v\u00eddeo corporativo<\/h2><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-container-block box-container\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-video\"><video controls controlslist=\"nodownload\" poster=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2024\/10\/immagine.png\" src=\"https:\/\/www.maccaferri.com\/wp-content\/uploads\/2024\/09\/MACCAFERRI-CORPORATE-DEF-V4A.mp4\"><\/video><\/figure><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-mac-h2-title-block block-txt-container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><h2 style=\"color:#212429;text-align:none\">Hist\u00f3ria<\/h2><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-container-block box-container\"><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p class=\"wp-block-paragraph\">Deslize para descobrir todos os cap\u00edtulos<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-container wp-block-column has-white-background-color has-background\"><div class=\"wp-block-mac-h2-title-block block-txt-container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><h2><\/h2><\/div><\/div><\/div><\/div><div class=\"container-fluid content-history\"><section class=\"timeline-carousel\"><div class=\"timeline-carousel__item-wrapper\" data-js=\"timeline-carousel\"><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>As origens<\/h5>Em 3 de maio de 1879, Raffaele Maccaferri estabeleceu a &#8220;Ditta Maccaferri Raffaele, Officina da Fabbro&#8221; em Lavino (Bolonha) para a produ\u00e7\u00e3o de artigos de ferro forjado.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/10\/HIS_01.png) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">1879<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>A inven\u00e7\u00e3o do gabi\u00e3o<\/h5>&#8220;Ditta Maccaferri&#8221; inventou e desenvolveu o famoso gabi\u00e3o. O antigo com\u00e9rcio artesanal se transforma em uma empresa industrial.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/10\/HIS_02.png) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">1894<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>In\u00edcio da expans\u00e3o<\/h5>A empresa come\u00e7a a expandir e abrir novos escrit\u00f3rios na It\u00e1lia e no exterior tamb\u00e9m atrav\u00e9s de fus\u00f5es e aquisi\u00e7\u00f5es. Os gabi\u00f5es saco originais foram seguidos pelo novo design em forma de caixa, que foi usado em muitos grandes projetos de obras p\u00fablicas.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/10\/HIS_03.png) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">1900 &#8211; 1945<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>Novo lan\u00e7amento e produtos<\/h5>Reorganiza\u00e7\u00e3o e relan\u00e7amento da produ\u00e7\u00e3o. Cria\u00e7\u00e3o de novos produtos: Maccaferri foi a primeira empresa na Europa a introduzir a galvaniza\u00e7\u00e3o &#8220;pesada&#8221;.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/11\/History_Relaunch-and-new-products-.jpg) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">1946 &#8211; 1966<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>Cinco continentes<\/h5>As opera\u00e7\u00f5es se expandiram pelos 5 continentes. Acelera\u00e7\u00e3o acentuada na diversifica\u00e7\u00e3o de produtos e localiza\u00e7\u00e3o. A nova abordagem de mercado est\u00e1 em conformidade com normas e especifica\u00e7\u00f5es internacionais.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/11\/h2.png) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">1967 &#8211; 1995<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>Evolu\u00e7\u00e3o<\/h5>In\u00edcio de parcerias sistem\u00e1ticas para oferecer aos clientes uma gama completa de solu\u00e7\u00f5es ambientais dur\u00e1veis e econ\u00f4micas.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/11\/History_evolution_2.jpg) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">1996 &#8211; 2005<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>Expans\u00e3o<\/h5>Expans\u00e3o geogr\u00e1fica atrav\u00e9s da localiza\u00e7\u00e3o e amplia\u00e7\u00e3o do portf\u00f3lio de solu\u00e7\u00f5es de engenharia sustent\u00e1veis.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/11\/h4.png) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">2006 &#8211; 2020<\/span>\n\t\t\t\t\t<\/div><\/div><div class=\"timeline-carousel__item\"><div class=\"timeline-carousel__item-inner mobile\"><h5>Novos desafios<\/h5>Desenvolvimento de novas solu\u00e7\u00f5es de valor agregado e ambientalmente corretas. A propriedade institucional refor\u00e7ou o DNA original da empresa que hoje, como no passado, apoia seu crescimento com um foco cont\u00ednuo na sustentabilidade, inova\u00e7\u00e3o, pesquisa e desenvolvimento.<\/div><div class=\"timeline-carousel__image\">\n\t\t\t\t\t\t\t<div class=\"media-wrapper media-wrapper--overlay\" style=\"background: url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/11\/h5.png) center center; background-size:cover;\"><\/div>\n\t\t\t\t\t\t\t<span class=\"year\">Hoje<\/span>\n\t\t\t\t\t<\/div><\/div><\/div><\/section><\/div><script type=\"text\/javascript\">\n    jQuery.js = function(el) {\n        return jQuery('[data-js=' + el + ']')\n    };\n\n    function timelinecarousel() {\n        jQuery.js('timeline-carousel').slick({\n            infinite: false,\n            arrows: false,\n            \/\/prevArrow: '<div class=\"slick-prev\"> <div class=\"btn mr-3 btn-warning d-flex justify-content-center align-items-center\"> <div>Previous<\/div><svg class=\"ml-1\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\"> <path d=\"M10.1,19.1l1.5-1.5L7,13h14.1v-2H7l4.6-4.6l-1.5-1.5L3,12L10.1,19.1z\"\/> <\/svg><\/div><\/div>',\n            \/\/nextArrow: '<div class=\"slick-next\"> <div class=\"btn btn-warning d-flex justify-content-center align-items-center\"> <svg class=\"mr-1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"> <path d=\"M 14 4.9296875 L 12.5 6.4296875 L 17.070312 11 L 3 11 L 3 13 L 17.070312 13 L 12.5 17.570312 L 14 19.070312 L 21.070312 12 L 14 4.9296875 z\"\/> <\/svg> <div>Next<\/div><\/div><\/div>',\n            dots: false,\n            autoplay: false,\n            speed: 1100,\n            slidesToShow: 4,\n            slidesToScroll: 4,\n            responsive: [{\n                    breakpoint: 1280,\n                    settings: {\n                        slidesToShow: 3,\n                        slidesToScroll: 3\n                    },\n                },\n                {\n                    breakpoint: 991.98,\n                    settings: {\n                        slidesToShow: 1,\n                        slidesToScroll: 1\n                    },\n                },\n            ],\n        });\n    }\n\n    timelinecarousel();\n<\/script><\/div><\/div><div class=\"wp-block-mac-editor-grid-block-image-transparent container-media box-container\"><div class=\"row\"><div class=\"col-12 col-lg-5 col-xl-5 col-xxl-5 title-box-txt\" style=\"text-align:default\"><h3 class=\"title\" style=\"color:#004857\">Cultivar e proteger o mundo de amanh\u00e3<\/h3><p class=\"description\" style=\"color:#004857\">Cultivar e proteger o mundo de amanh\u00e3: esta \u00e9 a nossa vis\u00e3o que transmite nosso compromisso com a sustentabilidade ambiental. Nossas solu\u00e7\u00f5es s\u00e3o projetadas e desenvolvidas com um olhar na qualidade de vida e na preserva\u00e7\u00e3o do meio ambiente e das comunidades para as gera\u00e7\u00f5es futuras.<\/p><div class=\"button-box-txt\" style=\"text-align:default\"><a href=\"https:\/\/www.maccaferri.com\/br\/sustentabilidade\/\" class=\"buttonurl\" rel=\"noopener\" style=\"background:#3DA3A7\"><span class=\"buttontext\">Mais sobre sustentabilidade<\/span><\/a><\/div><\/div><div class=\"col-12 offset-lg-1 offset-xl-1 offset-xxl-1 col-lg-6 col-xl-6 col-xxl-6 text-end\"><div class=\"box-image\"><img decoding=\"async\" class=\"image\" src=\"https:\/\/www.maccaferri.com\/aml\/wp-content\/uploads\/sites\/22\/2022\/09\/test-img-cta-right-e1670855658229.png\" alt=\"Image\"\/><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#004857\"><div class=\"wp-block-mac-editor-block container-fluid\"><div class=\"row\"><div class=\"col\"><div class=\"gts__picture\"><img decoding=\"async\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/06\/hero-home-1-1-5.png\" style=\"display:none\"\/><div class=\"gts__picture__image\" style=\"background-image:url(https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/06\/hero-home-1-1-5.png)\"><\/div><\/div><div class=\"container box-container\"><div class=\"row\"><div class=\"col title-box-txt\"><div style=\"text-align:center\"><h2 class=\"wp-block-mac-editor-block\" style=\"color:#FFFFFF\">INOVA\u00c7\u00c3O<\/h2><\/div><div style=\"text-align:center\"><p class=\"wp-block-mac-editor-block\" style=\"color:#FFFFFF\">Fomos fundados sob a premissa da inova\u00e7\u00e3o em 1893 iniciamos uma jornada em dire\u00e7\u00e3o a ela. Esta \u00e9 a nossa identidade: nos esfor\u00e7amos para estarmos atentos prara melhor solu\u00e7\u00e3o de engenharia e utilizamos o know-how e a pesquisa para satisfazer as necessidades dos cliente e mercados.<\/p><\/div><div style=\"text-align:right\"><a href=\"https:\/\/www.maccaferri.com\/br\/inovacao\/\" class=\"buttonurl\" rel=\"noopener\"><span class=\"buttontext\">Conhe\u00e7a mais<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-mac-carousel-team container\"><div class=\"box-container\"><h2 class=\"title-team\">Membros da Equipe Executiva<\/h2><\/div><div class=\"carouselteamsblock\"><div class=\"row\"><div id=\"carouselteam\" class=\"carousel slide\" data-bs-ride=\"false\" data-bs-interval=\"false\" data-bs-wrap=\"false\" data-bs-cycle=\"true\"><ol class=\"carousel-indicators\"><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"0\" class=\"active\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"1\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"2\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"3\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"4\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"5\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"6\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"7\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"8\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"9\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><li data-bs-target=\"#carouselteam\" data-bs-slide-to=\"10\" class=\"\" aria-current=\"true\" aria-label=\"Slide\"><\/li><\/ol><a class=\"carousel-control-prev w-aut\" href=\"#carouselteam\" role=\"button\" data-bs-slide=\"prev\">\n                     <span class=\"carousel-control-prev-icon\" aria-hidden=\"true\"><\/span>\n                  <\/a><a class=\"carousel-control-next w-aut\" href=\"#carouselteam\" role=\"button\" data-bs-slide=\"next\">\n                    <span class=\"carousel-control-next-icon\" aria-hidden=\"true\"><\/span>\n                  <\/a> <div class=\"carousel-inner container box-container\"><div class=\"carousel-item active\"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-1024x1024.jpg 1024w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-300x300.jpg 300w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-150x150.jpg 150w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-768x768.jpg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-1536x1536.jpg 1536w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/SAP03426-min-2-2048x2048.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Alexandre Marcos Texeira <\/h4><\/div><div class=\"jobdescription\">CEO Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-1024x1024.jpg 1024w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-300x300.jpg 300w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-150x150.jpg 150w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-768x768.jpg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-1536x1536.jpg 1536w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Filippo-2-2048x2048.jpg 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Filippo Adamo <\/h4><\/div><div class=\"jobdescription\">CFO Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-683x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-683x1024.jpg 683w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-200x300.jpg 200w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-768x1152.jpg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-1024x1536.jpg 1024w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-1365x2048.jpg 1365w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Fabricio-2-scaled.jpg 1706w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Fabricio Zambotto <\/h4><\/div><div class=\"jobdescription\">Diretor T\u00e9cnico \/ Comercial \u2013 Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"606\" height=\"652\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/thumbnail_image008.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/thumbnail_image008.jpg 606w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/thumbnail_image008-279x300.jpg 279w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/thumbnail_image008-112x120.jpg 112w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Ricardo Menegassi <\/h4><\/div><div class=\"jobdescription\">Diretor de Opera\u00e7\u00f5es \u2013 Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"655\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Jaime-2-1000x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Jaime-2-1000x1024.jpg 1000w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Jaime-2-293x300.jpg 293w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Jaime-2-768x786.jpg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Jaime-2-1501x1536.jpg 1501w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Jaime-2-2001x2048.jpg 2001w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Jaime da Silva Duran <\/h4><\/div><div class=\"jobdescription\">Gerente de Pesquisa e Desenvolvimento \u2013 Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"745\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Petrucio-2-880x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Petrucio-2-880x1024.jpg 880w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Petrucio-2-258x300.jpg 258w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Petrucio-2-768x893.jpg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Petrucio-2.jpg 1257w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Petrucio Jos\u00e9 dos Santos Junior <\/h4><\/div><div class=\"jobdescription\">Gerente do Departamento T\u00e9cnico \u2013 Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"852\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Paulo-2-769x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Paulo-2-769x1024.jpg 769w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Paulo-2-225x300.jpg 225w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Paulo-2-768x1022.jpg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Paulo-2-1154x1536.jpg 1154w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Paulo-2-rotated.jpg 1160w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Paulo C\u00e9sar Belesso Ferretti <\/h4><\/div><div class=\"jobdescription\">Gerente de Marketing \u2013 Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Patricia-2.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Patricia-2.png 300w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Patricia-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Patricia Rosa de Oliveira <\/h4><\/div><div class=\"jobdescription\">Gerente de RH \u2013 Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Moises-2.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Moises-2.jpg 450w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Moises-2-300x300.jpg 300w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Moises-2-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Mois\u00e9s Rog\u00e9rio Brand\u00e3o <\/h4><\/div><div class=\"jobdescription\">Gerente de TI - Am\u00e9rica Latina<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Thales-683x1024.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Thales-683x1024.jpeg 683w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Thales-200x300.jpeg 200w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Thales-768x1151.jpeg 768w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/01\/Thales.jpeg 854w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Thales Vitor da Silva <\/h4><\/div><div class=\"jobdescription\">Gerente Solu\u00e7\u00f5es Ambientais \u2013 Maccaferri do Brasil<\/div><\/div><\/div><\/div><\/div><div class=\"carousel-item \"><div class=\"col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\"><div class=\"card\"><div class=\"thumb-team\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/12\/Ivan.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/12\/Ivan.jpg 640w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/12\/Ivan-300x300.jpg 300w, https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/12\/Ivan-150x150.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/div><div class=\"content\"><div class=\"title\"><h4 class=\"p-0\"> Ivan Marassatto Masiero <\/h4><\/div><div class=\"jobdescription\">Gerente Constru\u00e7\u00e3o Civil e Arames Industriais \u2013 Maccaferri do Brasil<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column div-perguntas is-layout-flow wp-block-column-is-layout-flow\"><h2 class=\"has-text-align-center wp-block-post-title\">Perguntas frequentes<\/h2>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba O que \u00e9 a Maccaferri?<\/summary><p class=\"wp-block-paragraph\">A Maccaferri \u00e9 uma empresa multinacional com mais de 140 anos de hist\u00f3ria, especializada em solu\u00e7\u00f5es avan\u00e7adas para os mercados de <strong>constru\u00e7\u00e3o civil, geot\u00e9cnica e ambiental<\/strong>.<br>Fundada na segunda metade do s\u00e9culo XIX, a Maccaferri se destacou pela cria\u00e7\u00e3o dos Gabi\u00f5es, um sistema inovador de conten\u00e7\u00e3o que transformou a engenharia civil da \u00e9poca.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Qual \u00e9 a hist\u00f3ria da Maccaferri?<\/summary><p class=\"wp-block-paragraph\">Desde sua funda\u00e7\u00e3o, a Maccaferri tem trabalhado para oferecer solu\u00e7\u00f5es sustent\u00e1veis e dur\u00e1veis em projetos de infraestrutura ao redor do mundo.<br> A empresa est\u00e1 presente em mais de 130 pa\u00edses e continua a ser l\u00edder no setor, buscando inova\u00e7\u00e3o e excel\u00eancia em todas as suas solu\u00e7\u00f5es de engenharia, que incluem desde muros de conten\u00e7\u00e3o at\u00e9 obras hidr\u00e1ulicas e sistemas de mitiga\u00e7\u00e3o de quedas de rochas, sempre com <strong>foco em seguran\u00e7a e sustentabilidade<\/strong>.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Qual \u00e9 a vis\u00e3o da Maccaferri?<\/summary><p class=\"wp-block-paragraph\">A vis\u00e3o da Maccaferri \u00e9 cultivar e proteger o mundo de amanh\u00e3, com solu\u00e7\u00f5es que harmonizem a vida humana e a natureza. Temos um compromisso profundo com a sustentabilidade ambiental, buscando oferecer solu\u00e7\u00f5es inovadoras que atendam \u00e0s necessidades das gera\u00e7\u00f5es atuais e futuras.<\/p><\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Qual \u00e9 a miss\u00e3o da Maccaferri?<\/summary><p class=\"wp-block-paragraph\">Buscar a excel\u00eancia atrav\u00e9s da melhoria cont\u00ednua enquanto entregamos a nossos clientes solu\u00e7\u00f5es inovadoras, avan\u00e7adas e compat\u00edveis com o meio ambiente.<br>Estamos comprometidos com a <strong>seguran\u00e7a, qualidade e sustentabilidade excepcionais<\/strong>, para criar valor para todos nossos clientes, bem como para nossa comunidade.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Quais s\u00e3o os principais produtos e solu\u00e7\u00f5es oferecidos pela Maccaferri?<\/summary><p class=\"wp-block-paragraph\">A Maccaferri oferece uma ampla gama de produtos e solu\u00e7\u00f5es voltados para a engenharia civil, geot\u00e9cnica e ambiental, com foco em durabilidade e sustentabilidade. Entre os principais produtos, destacam-se:<\/p>\n\n<ul class=\"wp-block-list\"><li>&#8211; Gabi\u00f5es: estruturas de conten\u00e7\u00e3o de solo formadas por malhas hexagonais de dupla tor\u00e7\u00e3o, utilizadas em muros de conten\u00e7\u00e3o em obras no meio geot\u00e9cnico, hidr\u00e1ulico e ambiental;<\/li>\n\n<li>&#8211; Geossint\u00e9ticos: produtos como geot\u00eaxteis, geomembranas, geocompostos e geogrelhas para refor\u00e7o de solos, impermeabiliza\u00e7\u00e3o e drenagem;<\/li>\n\n<li>&#8211; Sistemas de mitiga\u00e7\u00e3o de quedas de rochas: barreiras projetadas para proteger infraestruturas de quedas de pedras e fluxos de detritos;<\/li>\n\n<li>&#8211; Solos refor\u00e7ados: solu\u00e7\u00f5es para melhorar a estabilidade de solos inst\u00e1veis e prevenir recalques em obras de grande porte.<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Esses produtos s\u00e3o aplicados em obras hidr\u00e1ulicas, prote\u00e7\u00e3o ambiental, infraestrutura urbana, minera\u00e7\u00e3o, entre outras \u00e1reas, com foco na seguran\u00e7a e na sustentabilidade dos projetos.<\/p><\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Como a Maccaferri contribui para a sustentabilidade ambiental?<\/summary><p class=\"wp-block-paragraph\">A sustentabilidade ambiental \u00e9 um dos pilares da Maccaferri e est\u00e1 presente em todas as solu\u00e7\u00f5es desenvolvidas pela empresa. Cada produto, desde a produ\u00e7\u00e3o de <strong>gabi\u00f5es at\u00e9 os sistemas de drenagem de solos<\/strong>, \u00e9 projetado com um olhar voltado para a preserva\u00e7\u00e3o dos recursos naturais.<br>Dito isso, a empresa busca n\u00e3o apenas atender \u00e0s necessidades dos clientes, mas tamb\u00e9m garantir o respeito e a prote\u00e7\u00e3o ao meio ambiente.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Quais iniciativas a Maccaferri adota para reduzir seu impacto ambiental?<\/summary><p class=\"wp-block-paragraph\">A Maccaferri investe em tecnologias sustent\u00e1veis, como o uso de materiais recicl\u00e1veis e a redu\u00e7\u00e3o da pegada de carbono nas suas opera\u00e7\u00f5es.<br>Tamb\u00e9m <strong>promovemos a gest\u00e3o eficiente da \u00e1gua, reduzimos a eros\u00e3o do solo<\/strong> e trabalhamos para minimizar os impactos ambientais em obras de grande porte, sempre com foco em solu\u00e7\u00f5es que atendam aos desafios ambientais globais.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Como a Maccaferri integra sustentabilidade e inova\u00e7\u00e3o?<\/summary><p class=\"wp-block-paragraph\">A Maccaferri busca constantemente integrar a sustentabilidade ambiental com inova\u00e7\u00e3o, desenvolvendo solu\u00e7\u00f5es que atendam aos desafios de hoje e tamb\u00e9m estejam preparadas para os desafios do futuro.<br> Nos dedicamos a criar solu\u00e7\u00f5es sustent\u00e1veis e inovadoras, garantindo que nossos projetos parceiros contribuam para a preserva\u00e7\u00e3o ambiental e para um desenvolvimento mais sustent\u00e1vel a longo prazo.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Como a Maccaferri garante a qualidade e confiabilidade de suas solu\u00e7\u00f5es?<\/summary><p class=\"wp-block-paragraph\">A Maccaferri adota processos rigorosos de <strong>controle de qualidade e pesquisa<\/strong> constante para garantir que suas solu\u00e7\u00f5es atendam aos mais altos padr\u00f5es de desempenho e seguran\u00e7a.<br> Cada produto passa por testes de resist\u00eancia e durabilidade, sendo desenvolvido com base em pesquisa t\u00e9cnica e no know-how adquirido ao longo de mais de 140 anos de experi\u00eancia.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>\u25ba Como a equipe da Maccaferri contribui para o desenvolvimento de solu\u00e7\u00f5es confi\u00e1veis?<\/summary><p class=\"wp-block-paragraph\">Nossa equipe t\u00e9cnica, composta por engenheiros, especialistas em geotecnia, engenheiros civis, profissionais qualificados em sustentabilidade ambiental e especialistas em pesquisa e desenvolvimento, trabalha em colabora\u00e7\u00e3o com nossos clientes para oferecer solu\u00e7\u00f5es personalizadas, sempre alinhadas \u00e0s necessidades espec\u00edficas de cada projeto.<br> Nosso time \u00e9 altamente capacitado e possui <strong>vasta experi\u00eancia t\u00e9cnica<\/strong>, o que garante que as solu\u00e7\u00f5es que desenvolvemos sejam precisas, eficazes e confi\u00e1veis.<\/p>\n<\/details><\/div><\/div><style>\n.div-perguntas {\n  justify-content: center;\n  margin-top: 40px;\n  width: 100%;\n}\n.div-perguntas .wp-block-column {\n  width: 500px; \n  border: 1px solid #ddd; \n  border-radius: 8px; \n  padding: 20px;\n  box-sizing: border-box;\n  background-color: #fff; \n  box-shadow: 0 4px 6px rgba(0,0,0,0.05); \n}\n.div-perguntas h2 {\n  text-align: center;\n  margin-bottom: 20px;\n  font-size: 24px;\n  font-weight: 600;\n}\n.div-perguntas details summary {\n  cursor: pointer;\n  font-size: 18px;\n  display: flex;\n  align-items: center;\n  justify-content: space-between;\n  padding: 12px 0;\n  border-bottom: 1px solid #eee;\n  list-style: none;\n}\n.div-perguntas details p {\n  padding: 10px 0px 10px 20px;\n  margin: 0;\n}\n<\/style>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-86289","page","type-page","status-publish","hentry"],"acf":{"uuid_products":"","product-documents":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perguntas frequentes - Maccaferri Brasil<\/title>\n<meta name=\"description\" content=\"0Sobre N\u00f3sSustentabilidade ambiental movem as nossas solu\u00e7\u00f5es Vis\u00e3o&amp; Miss\u00e3oNa segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perguntas frequentes\" \/>\n<meta property=\"og:description\" content=\"0Sobre N\u00f3sSustentabilidade ambiental movem as nossas solu\u00e7\u00f5es Vis\u00e3o&amp; Miss\u00e3oNa segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maccaferri.com\/br\/sobre-nos\/\" \/>\n<meta property=\"og:site_name\" content=\"Maccaferri Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T20:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perguntas frequentes - Maccaferri Brasil","description":"0Sobre N\u00f3sSustentabilidade ambiental movem as nossas solu\u00e7\u00f5es Vis\u00e3o&amp; Miss\u00e3oNa segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"pt_BR","og_type":"article","og_title":"Perguntas frequentes","og_description":"0Sobre N\u00f3sSustentabilidade ambiental movem as nossas solu\u00e7\u00f5es Vis\u00e3o&amp; Miss\u00e3oNa segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente","og_url":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/","og_site_name":"Maccaferri Brasil","article_modified_time":"2025-10-30T20:50:28+00:00","og_image":[{"url":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/","url":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/","name":"Perguntas frequentes - Maccaferri Brasil","isPartOf":{"@id":"https:\/\/www.maccaferri.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/#primaryimage"},"image":{"@id":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg","datePublished":"2022-07-28T13:26:07+00:00","dateModified":"2025-10-30T20:50:28+00:00","description":"0Sobre N\u00f3sSustentabilidade ambiental movem as nossas solu\u00e7\u00f5es Vis\u00e3o&amp; Miss\u00e3oNa segunda metade do s\u00e9culo XIX, criamos os Gabi\u00f5es e mudamos drasticamente","breadcrumb":{"@id":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maccaferri.com\/br\/sobre-nos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/#primaryimage","url":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg","contentUrl":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2023\/07\/header-about-us-maccaferri-nurturing-1-5.jpg","width":1000,"height":793},{"@type":"BreadcrumbList","@id":"https:\/\/www.maccaferri.com\/br\/sobre-nos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.maccaferri.com\/br\/"},{"@type":"ListItem","position":2,"name":"Perguntas frequentes"}]},{"@type":"WebSite","@id":"https:\/\/www.maccaferri.com\/br\/#website","url":"https:\/\/www.maccaferri.com\/br\/","name":"Maccaferri Brasil","description":"","publisher":{"@id":"https:\/\/www.maccaferri.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maccaferri.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.maccaferri.com\/br\/#organization","name":"Maccaferri do Brasil","alternateName":"Maccaferri","url":"https:\/\/www.maccaferri.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.maccaferri.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/07\/logo-maccaferri.png","contentUrl":"https:\/\/www.maccaferri.com\/br\/wp-content\/uploads\/2022\/07\/logo-maccaferri.png","width":152,"height":32,"caption":"Maccaferri do Brasil"},"image":{"@id":"https:\/\/www.maccaferri.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/pages\/86289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/comments?post=86289"}],"version-history":[{"count":44,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/pages\/86289\/revisions"}],"predecessor-version":[{"id":110940,"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/pages\/86289\/revisions\/110940"}],"wp:attachment":[{"href":"https:\/\/www.maccaferri.com\/br\/wp-json\/wp\/v2\/media?parent=86289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}